{"id":16760,"date":"2022-02-28T15:25:21","date_gmt":"2022-02-28T14:25:21","guid":{"rendered":"https:\/\/frv.com\/?p=16760"},"modified":"2023-07-12T13:52:28","modified_gmt":"2023-07-12T11:52:28","slug":"frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano","status":"publish","type":"post","link":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/","title":{"rendered":"FRV, Energy Toolbase &#038; Ecopulse launch pioneering \u2018Energy-Storage-as-a-Service\u2019 project for the Mexican industrial sector"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-pl\">Przepraszamy, ten wpis jest dost\u0119pny tylko w j\u0119zyku <a href=\"https:\/\/frv.com\/en\/wp-json\/wp\/v2\/posts\/16760\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> i <a href=\"https:\/\/frv.com\/es\/wp-json\/wp\/v2\/posts\/16760\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Przepraszamy, ten wpis jest dost\u0119pny tylko w j\u0119zyku English i Espa\u00f1ol.<\/p>\n","protected":false},"author":9,"featured_media":17951,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,4,6],"tags":[45,46,47,43,44],"class_list":["post-16760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-innovacion","category-press-releases","category-projects","tag-almacenamiento","tag-baterias","tag-bess","tag-ensaas","tag-storage"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FRV lanza un proyecto pionero de almacenamiento de energ\u00eda en Mexico<\/title>\n<meta name=\"description\" content=\"FRV lanza su proyecto EnSaaS enfocado en el sector industrial mexicano, que permitir\u00e1 optimizar el consumo energ\u00e9tico y un importante ahorro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FRV lanza un proyecto pionero de almacenamiento de energ\u00eda en Mexico\" \/>\n<meta property=\"og:description\" content=\"FRV lanza su proyecto EnSaaS enfocado en el sector industrial mexicano, que permitir\u00e1 optimizar el consumo energ\u00e9tico y un importante ahorro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"FRV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FRV.Official\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-28T14:25:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-12T11:52:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frv.com\/wp-content\/uploads\/2023\/07\/FRV-X-EnSaaS-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1436\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Guillermo Agull\u00f3 Beltr\u00e1n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FotowatioRV\" \/>\n<meta name=\"twitter:site\" content=\"@FotowatioRV\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guillermo Agull\u00f3 Beltr\u00e1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frv.com\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frv.com\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/\"},\"author\":{\"name\":\"Guillermo Agull\u00f3 Beltr\u00e1n\",\"@id\":\"https:\\\/\\\/frv.com\\\/#\\\/schema\\\/person\\\/cc8a0abdaae9c766e2b875c29dc3bc51\"},\"headline\":\"FRV, Energy Toolbase &#038; Ecopulse launch pioneering \u2018Energy-Storage-as-a-Service\u2019 project for the Mexican industrial sector\",\"datePublished\":\"2022-02-28T14:25:21+00:00\",\"dateModified\":\"2023-07-12T11:52:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frv.com\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/\"},\"wordCount\":2427,\"image\":{\"@id\":\"https:\\\/\\\/frv.com\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frv.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/FRV-X-EnSaaS-1-e1745923028843.webp\",\"keywords\":[\"Almacenamiento\",\"Bater\u00edas\",\"BESS\",\"EnSaas\",\"Storage\"],\"articleSection\":[\"FRV-X\",\"Notas de prensa\",\"Proyectos\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frv.com\\\/pl\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/\",\"url\":\"https:\\\/\\\/frv.com\\\/pl\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/\",\"name\":\"FRV lanza un proyecto pionero de almacenamiento de energ\u00eda en Mexico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frv.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frv.com\\\/pl\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frv.com\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frv.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/FRV-X-EnSaaS-1-e1745923028843.webp\",\"datePublished\":\"2022-02-28T14:25:21+00:00\",\"dateModified\":\"2023-07-12T11:52:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frv.com\\\/#\\\/schema\\\/person\\\/cc8a0abdaae9c766e2b875c29dc3bc51\"},\"description\":\"FRV lanza su proyecto EnSaaS enfocado en el sector industrial mexicano, que permitir\u00e1 optimizar el consumo energ\u00e9tico y un importante ahorro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frv.com\\\/pl\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/frv.com\\\/pl\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/frv.com\\\/pl\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frv.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/FRV-X-EnSaaS-1-e1745923028843.webp\",\"contentUrl\":\"https:\\\/\\\/frv.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/FRV-X-EnSaaS-1-e1745923028843.webp\",\"width\":800,\"height\":411},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frv.com\\\/pl\\\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/frv.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FRV, Energy Toolbase y Ecopulse lanzan un proyecto pionero de almacenamiento de energ\u00eda para el sector industrial mexicano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frv.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/frv.com\\\/pl\\\/\",\"name\":\"FRV\",\"description\":\"The future happens here\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frv.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frv.com\\\/#\\\/schema\\\/person\\\/cc8a0abdaae9c766e2b875c29dc3bc51\",\"name\":\"Guillermo Agull\u00f3 Beltr\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/835735a78c471af7e3c52c5167eeadc69bb5b75fff2f129bc038828f7dae5178?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/835735a78c471af7e3c52c5167eeadc69bb5b75fff2f129bc038828f7dae5178?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/835735a78c471af7e3c52c5167eeadc69bb5b75fff2f129bc038828f7dae5178?s=96&d=mm&r=g\",\"caption\":\"Guillermo Agull\u00f3 Beltr\u00e1n\"},\"url\":\"https:\\\/\\\/frv.com\\\/pl\\\/author\\\/guillermo-agullofrv-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FRV lanza un proyecto pionero de almacenamiento de energ\u00eda en Mexico","description":"FRV lanza su proyecto EnSaaS enfocado en el sector industrial mexicano, que permitir\u00e1 optimizar el consumo energ\u00e9tico y un importante ahorro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/","og_locale":"pl_PL","og_type":"article","og_title":"FRV lanza un proyecto pionero de almacenamiento de energ\u00eda en Mexico","og_description":"FRV lanza su proyecto EnSaaS enfocado en el sector industrial mexicano, que permitir\u00e1 optimizar el consumo energ\u00e9tico y un importante ahorro","og_url":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/en\/","og_site_name":"FRV","article_publisher":"https:\/\/www.facebook.com\/FRV.Official","article_published_time":"2022-02-28T14:25:21+00:00","article_modified_time":"2023-07-12T11:52:28+00:00","og_image":[{"width":1436,"height":738,"url":"https:\/\/frv.com\/wp-content\/uploads\/2023\/07\/FRV-X-EnSaaS-1.webp","type":"image\/webp"}],"author":"Guillermo Agull\u00f3 Beltr\u00e1n","twitter_card":"summary_large_image","twitter_creator":"@FotowatioRV","twitter_site":"@FotowatioRV","twitter_misc":{"Napisane przez":"Guillermo Agull\u00f3 Beltr\u00e1n","Szacowany czas czytania":"6 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frv.com\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/#article","isPartOf":{"@id":"https:\/\/frv.com\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/"},"author":{"name":"Guillermo Agull\u00f3 Beltr\u00e1n","@id":"https:\/\/frv.com\/#\/schema\/person\/cc8a0abdaae9c766e2b875c29dc3bc51"},"headline":"FRV, Energy Toolbase &#038; Ecopulse launch pioneering \u2018Energy-Storage-as-a-Service\u2019 project for the Mexican industrial sector","datePublished":"2022-02-28T14:25:21+00:00","dateModified":"2023-07-12T11:52:28+00:00","mainEntityOfPage":{"@id":"https:\/\/frv.com\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/"},"wordCount":2427,"image":{"@id":"https:\/\/frv.com\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/#primaryimage"},"thumbnailUrl":"https:\/\/frv.com\/wp-content\/uploads\/2023\/07\/FRV-X-EnSaaS-1-e1745923028843.webp","keywords":["Almacenamiento","Bater\u00edas","BESS","EnSaas","Storage"],"articleSection":["FRV-X","Notas de prensa","Proyectos"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/","url":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/","name":"FRV lanza un proyecto pionero de almacenamiento de energ\u00eda en Mexico","isPartOf":{"@id":"https:\/\/frv.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/#primaryimage"},"image":{"@id":"https:\/\/frv.com\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/#primaryimage"},"thumbnailUrl":"https:\/\/frv.com\/wp-content\/uploads\/2023\/07\/FRV-X-EnSaaS-1-e1745923028843.webp","datePublished":"2022-02-28T14:25:21+00:00","dateModified":"2023-07-12T11:52:28+00:00","author":{"@id":"https:\/\/frv.com\/#\/schema\/person\/cc8a0abdaae9c766e2b875c29dc3bc51"},"description":"FRV lanza su proyecto EnSaaS enfocado en el sector industrial mexicano, que permitir\u00e1 optimizar el consumo energ\u00e9tico y un importante ahorro","breadcrumb":{"@id":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/"]]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/#primaryimage","url":"https:\/\/frv.com\/wp-content\/uploads\/2023\/07\/FRV-X-EnSaaS-1-e1745923028843.webp","contentUrl":"https:\/\/frv.com\/wp-content\/uploads\/2023\/07\/FRV-X-EnSaaS-1-e1745923028843.webp","width":800,"height":411},{"@type":"BreadcrumbList","@id":"https:\/\/frv.com\/pl\/frv-energy-toolbase-y-ecopulse-lanzan-un-proyecto-pionero-de-almacenamiento-de-energia-para-el-sector-industrial-mexicano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frv.com\/pl\/"},{"@type":"ListItem","position":2,"name":"FRV, Energy Toolbase y Ecopulse lanzan un proyecto pionero de almacenamiento de energ\u00eda para el sector industrial mexicano"}]},{"@type":"WebSite","@id":"https:\/\/frv.com\/pl\/#website","url":"https:\/\/frv.com\/pl\/","name":"FRV","description":"The future happens here","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frv.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Person","@id":"https:\/\/frv.com\/#\/schema\/person\/cc8a0abdaae9c766e2b875c29dc3bc51","name":"Guillermo Agull\u00f3 Beltr\u00e1n","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/secure.gravatar.com\/avatar\/835735a78c471af7e3c52c5167eeadc69bb5b75fff2f129bc038828f7dae5178?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/835735a78c471af7e3c52c5167eeadc69bb5b75fff2f129bc038828f7dae5178?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/835735a78c471af7e3c52c5167eeadc69bb5b75fff2f129bc038828f7dae5178?s=96&d=mm&r=g","caption":"Guillermo Agull\u00f3 Beltr\u00e1n"},"url":"https:\/\/frv.com\/pl\/author\/guillermo-agullofrv-com\/"}]}},"search_content":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-pl\">Przepraszamy, ten wpis jest dost\u0119pny tylko w j\u0119zyku <a href=\"https:\/\/frv.com\/en\/wp-json\/wp\/v2\/posts\/16760\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> i <a href=\"https:\/\/frv.com\/es\/wp-json\/wp\/v2\/posts\/16760\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espa\u00f1ol<\/a>.<\/p>","search_term":"","_links":{"self":[{"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/posts\/16760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/comments?post=16760"}],"version-history":[{"count":7,"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/posts\/16760\/revisions"}],"predecessor-version":[{"id":17952,"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/posts\/16760\/revisions\/17952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/media\/17951"}],"wp:attachment":[{"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/media?parent=16760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/categories?post=16760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frv.com\/pl\/wp-json\/wp\/v2\/tags?post=16760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}